{"id":82,"date":"2023-09-10T04:53:59","date_gmt":"2023-09-10T04:53:59","guid":{"rendered":"https:\/\/wpolive.com\/suqat\/?page_id=82"},"modified":"2023-09-14T06:15:24","modified_gmt":"2023-09-14T06:15:24","slug":"home-style-2","status":"publish","type":"page","link":"https:\/\/wpolive.com\/suqat\/home-style-2\/","title":{"rendered":"Home Style 2"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"82\" class=\"elementor elementor-82\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d5c95c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3d5c95c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c480e4c\" data-id=\"c480e4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57cbe04 elementor-widget elementor-widget-wpo-suqat_slider\" data-id=\"57cbe04\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\t<div class=\"suqat-hero wpo-hero-slider\">\r\n\t\t\t<div class=\"swiper-container\">\r\n\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slide-inner slide-bg-image\" data-background=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/slide-4.jpg\">\r\n\t\t\t\t\t\t\t<!-- <div class=\"gradient-overlay\"><\/div> -->\r\n\t\t\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t\t\t\t\t<div class=\"slide-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"300\" class=\"slide-title-sub\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"fi flaticon-placeholder\"><\/i>Tucson, Arizona(AZ), 85719<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"300\" class=\"slide-title\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h2>Your Exclusive Haven of Luxury and Comfort<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"500\" class=\"slide-btns\">\r\n\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"500\" class=\"slide-btns\"><a href=\"#\"   class=\"theme-btn\" >get started<\/a><\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div> <!-- end slide-inner -->\r\n\t\t\t\t\t<\/div> <!-- end swiper-slide -->\r\n\r\n\t\t\t\t\t<!-- end swiper-slide -->\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slide-inner slide-bg-image\" data-background=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/slide-5.jpg\">\r\n\t\t\t\t\t\t\t<!-- <div class=\"gradient-overlay\"><\/div> -->\r\n\t\t\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t\t\t\t\t<div class=\"slide-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"300\" class=\"slide-title-sub\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"fi flaticon-placeholder\"><\/i>Tucson, Arizona(AZ), 85719<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"300\" class=\"slide-title\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h2>Your Exclusive Haven of Luxury and Comfort<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"500\" class=\"slide-btns\">\r\n\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"500\" class=\"slide-btns\"><a href=\"#\"   class=\"theme-btn\" >get started<\/a><\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div> <!-- end slide-inner -->\r\n\t\t\t\t\t<\/div> <!-- end swiper-slide -->\r\n\r\n\t\t\t\t\t<!-- end swiper-slide -->\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slide-inner slide-bg-image\" data-background=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/slide-7.jpg\">\r\n\t\t\t\t\t\t\t<!-- <div class=\"gradient-overlay\"><\/div> -->\r\n\t\t\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t\t\t\t\t<div class=\"slide-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"300\" class=\"slide-title-sub\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span><i class=\"fi flaticon-placeholder\"><\/i>Tucson, Arizona(AZ), 85719<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"300\" class=\"slide-title\">\r\n\t\t\t\t\t\t\t\t\t\t\t<h2>Your Exclusive Haven of Luxury and Comfort<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"500\" class=\"slide-btns\">\r\n\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax=\"500\" class=\"slide-btns\"><a href=\"#\"   class=\"theme-btn\" >get started<\/a><\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div> <!-- end slide-inner -->\r\n\t\t\t\t\t<\/div> <!-- end swiper-slide -->\r\n\r\n\t\t\t\t\t<!-- end swiper-slide -->\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<!-- end swiper-wrapper -->\r\n\t\t\t\t\t\t\t\t\t<!-- swipper controls -->\r\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\r\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\r\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<div class=\"hero-right-video\">\r\n\t\t\t\t\t<div class=\"hero-right-video-wrap\">\r\n\t\t\t\t\t\t<div class=\"circular-text text-roted\">\r\n\t\t\t\t\t\t\t<p class=\"text\">Watch Intro Video<\/p>\r\n\t\t\t\t\t\t\t<a href=\"#\" class=\"video-btn\" data-type=\"iframe\"><\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afb5ed3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"afb5ed3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3243eb0\" data-id=\"3243eb0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0d846d elementor-widget elementor-widget-wpo-suqat_feature\" data-id=\"f0d846d\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_feature.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"suqat-feature features-content\">\n\t\t\t<div class=\"container\">\n\t\t\t\t<div class=\"features-content-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"features-content-item\">\n\t\t\t\t\t\t<h2>5<\/h2><span>bed room<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"features-content-item\">\n\t\t\t\t\t\t<h2>2<\/h2><span>full baths<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"features-content-item\">\n\t\t\t\t\t\t<h2>4<\/h2><span>half baths<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"features-content-item\">\n\t\t\t\t\t\t<h2>2<\/h2><span>car parking<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"features-content-item\">\n\t\t\t\t\t\t<h2>6,382<\/h2><span>square feet<\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"features-content-item\">\n\t\t\t\t\t\t\t<a href=\"#\" class=\"theme-btn\"  >take a tour<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2c0355 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f2c0355\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db3d7dd\" data-id=\"db3d7dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85752b5 elementor-widget elementor-widget-wpo-suqat_service\" data-id=\"85752b5\" data-element_type=\"widget\" data-settings=\"{&quot;title_image&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/wpolive.com\\\/suqat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/left-image.jpg&quot;,&quot;id&quot;:342,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;title_image2&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/wpolive.com\\\/suqat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/title2.jpg&quot;,&quot;id&quot;:346,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;}}\" data-widget_type=\"wpo-suqat_service.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"suqat-service wpo-service-section-s2\">\r\n\t\t\t\t\t<div class=\"container\">\r\n\t\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t\t<div class=\"col-lg-4\">\r\n\t\t\t\t\t\t\t\t<div class=\"left-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/left-image.jpg\" alt=\"\">\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"col-lg-8\">\r\n\t\t\t\t\t\t\t\t<div class=\"wpo-service-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"row justify-content-center\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-7\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-section-title-s2\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h2>modern <span>facilities<\/span> of the property.<\/h2>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-5\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-section-title-img\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/title2.jpg\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-6 col-md-6 col-12\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Concrete-Tile.svg\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/service\/concrete-tile\/\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tConcrete Tile\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>The property boasts state-of-the-art amenities, including a sleek fitness center, smart home technology.<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-6 col-md-6 col-12\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Family-Room.svg\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/service\/family-room\/\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tFamily Room\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Spacious family room with cozy d\u00e9cor, ample seating, and entertainment options for quality bonding.<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-6 col-md-6 col-12\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Guest-Quaters.svg\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/service\/guest-quarters\/\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tGuest Quarters\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Elegant guest quarters with all the comforts of home, ensuring a memorable stay for visitors.<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-6 col-md-6 col-12\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Heated-Floors.svg\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/service\/heated-floors\/\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tHeated Floors\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Heated floors provide a warm, cozy ambiance, especially in colder seasons, enhancing comfort.<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-6 col-md-6 col-12\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Swimming-Pool.svg\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/service\/swimming-pool\/\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tSwimming Pool\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>The sparkling swimming pool offers a refreshing escape, complete with loungers, and stunning views.<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-6 col-md-6 col-12\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Ocean-View.svg\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-service-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/service\/ocean-view\/\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tOcean View\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Ocean view from every room, creating a serene and captivating backdrop for an unforgettable stay.<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84e242a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"84e242a\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b30f52\" data-id=\"8b30f52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d246056 elementor-widget elementor-widget-wpo-suqat_floortabs\" data-id=\"d246056\" data-element_type=\"widget\" data-settings=\"{&quot;tab_image&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/wpolive.com\\\/suqat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/plan-2.png&quot;,&quot;id&quot;:414,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;}}\" data-widget_type=\"wpo-suqat_floortabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"wpo-plan-section-s2\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row align-items-center\">\n\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t\t\t<div class=\"wpo-section-title-s2\">\n\t\t\t\t\t\t\t\t<h2> squat <span>property<\/span> floor plans.<\/h2>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wpo-plan-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t<div class=\"col-lg-5 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-tab-menu\">\n\t\t\t\t\t\t\t\t\t\t\t<ul class=\"nav nav-tabs\" id=\"myTab\" role=\"tablist\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"nav-link \" id=\"tabs-2\" data-bs-toggle=\"tab\" href=\"#tabs2\" role=\"tab\" aria-controls=\"tabs2\" aria-selected=\"true\">Basement<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"nav-link active in\" id=\"tabs-3\" data-bs-toggle=\"tab\" href=\"#tabs3\" role=\"tab\" aria-controls=\"tabs3\" aria-selected=\"true\">ground floor<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"nav-link \" id=\"tabs-4\" data-bs-toggle=\"tab\" href=\"#tabs4\" role=\"tab\" aria-controls=\"tabs4\" aria-selected=\"true\">1st floor<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"nav-link \" id=\"tabs-5\" data-bs-toggle=\"tab\" href=\"#tabs5\" role=\"tab\" aria-controls=\"tabs5\" aria-selected=\"true\">2nd floor<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"nav-link \" id=\"tabs-6\" data-bs-toggle=\"tab\" href=\"#tabs6\" role=\"tab\" aria-controls=\"tabs6\" aria-selected=\"true\">rooftop<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-lg-7 col-md-6\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"tab-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div role=\"tabpanel\" class=\"tab-pane fade in \" id=\"tabs2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Square feet<span>3,485<\/span><\/li><li>Car Parking<span>2<\/span><\/li><li>half baths<span>3<\/span><\/li><li>Full baths<span>4<\/span><\/li><li>Bed Room<span>3<\/span><\/li>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\"   class=\"tab-btn\" >started now<\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div role=\"tabpanel\" class=\"tab-pane fade in show active\" id=\"tabs3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Square feet<span>2,537<\/span><\/li><li>Car Parking<span>2<\/span><\/li><li>half baths<span>2<\/span><\/li><li>Full baths<span>3<\/span><\/li><li>Bed Room<span>3<\/span><\/li>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\"   class=\"tab-btn\" >started now<\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div role=\"tabpanel\" class=\"tab-pane fade in \" id=\"tabs4\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Square feet<span>5,738<\/span><\/li><li>Car Parking<span>3<\/span><\/li><li>half baths<span>4<\/span><\/li><li>Full baths<span>5<\/span><\/li><li>Bed Room<span>3<\/span><\/li>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\"   class=\"tab-btn\" >started now<\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div role=\"tabpanel\" class=\"tab-pane fade in \" id=\"tabs5\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Square feet<span>2,537<\/span><\/li><li>Car Parking<span>2<\/span><\/li><li>half baths<span>2<\/span><\/li><li>Full baths<span>3<\/span><\/li><li>Bed Room<span>3<\/span><\/li>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\"   class=\"tab-btn\" >started now<\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div role=\"tabpanel\" class=\"tab-pane fade in \" id=\"tabs6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpo-plan-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Square feet<span>2,537<\/span><\/li><li>Car Parking<span>2<\/span><\/li><li>half baths<span>2<\/span><\/li><li>Full baths<span>3<\/span><\/li><li>Bed Room<span>3<\/span><\/li>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\"   class=\"tab-btn\" >started now<\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t\t\t<div class=\"wpo-plan-img\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/plan-2.png\" alt=\"\">\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f8ce4b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5f8ce4b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-369ed20\" data-id=\"369ed20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9f33ba elementor-widget elementor-widget-wpo-suqat_payment\" data-id=\"b9f33ba\" data-element_type=\"widget\" data-settings=\"{&quot;bg_image&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/wpolive.com\\\/suqat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/payment-bg.png&quot;,&quot;id&quot;:242,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;}}\" data-widget_type=\"wpo-suqat_payment.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wpo-payment-section-s2\">\n    \t<div class=\"container\">\n        <div class=\"row justify-content-center\">\n            <div class=\"col col-lg-6 col-12\">\n                <div class=\"wpo-section-title\">\n                   <small>estimate<\/small><h2>your <span>payment<\/span> Estimate<\/h2>                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"wpo-payment-wrap\"  style=\"background-image: url( https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/payment-bg.png );\">\n            <div class=\"row\">\n                <div class=\"col col-lg-12\">\n                    <div class=\"payment-form-area\">\n                        <div class=\"form-group\">\n                          <label>purchase price:<\/label>\n                            <input type=\"number\" value=\"6382\" id=\"purchase_price\">\n                        <\/div>\n                        <div class=\"form-group\">\n                           <label>down payment %:<\/label>\n                            <input type=\"number\" value=\"20\" id=\"down_payment\">\n                        <\/div>\n                        <div class=\"form-group\">\n                           <label>loan term Year:<\/label>\n                            <input type=\"number\" value=\"35\" id=\"loan_term\">\n                        <\/div>\n                        <div class=\"form-group\">\n                            <label>interest rate %:<\/label>\n                            <input type=\"number\" value=\"5.5\" id=\"interest_rate\">\n                        <\/div>\n                        <div class=\"form-group text-center\">\n                            <button class=\"theme-btn\" onclick=\"estimatePayment()\">Estimate payment<\/button>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col col-lg-12 col-12\">\n                    <div class=\"payment-result\">\n                        <div class=\"result-item\">\n                           <span>down payment %:<\/span>\n                            <h3 id=\"down_payment_value\">$1276.40<\/h3>\n                        <\/div>\n                        <div class=\"result-item\">\n                            <span>monthly payment:<\/span>\n                            <h3 id=\"monthly_payment_value\">$12.82<\/h3>\n                        <\/div>\n                        <div class=\"result-item\">\n                            <span>Total loan amount:<\/span>\n                            <h3 id=\"load_amount_value\">$5386.41<\/h3>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    \t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e25e3e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1e25e3e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8f7e99\" data-id=\"d8f7e99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-157ce7a elementor-widget elementor-widget-wpo-suqat_project\" data-id=\"157ce7a\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_project.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t<div class=\"wpo-property-section\">\n\t\t\t<div class=\"container\">\n          <div class=\"row\">\n              <div class=\"col-lg-7 col-12\">\n                  <div class=\"wpo-section-title\">\n                      <h2>Discover our <span>featured<\/span> property<\/h2>                  <\/div>\n              <\/div>\n          <\/div>\n      <\/div>\n    \t<div class=\"container\">\n        <div class=\"property-slider property-active owl-carousel\">\n\t\t    \t\t\t\t\t\t\t   <div class=\"card-single\">\n                <div class=\"image\">\n                  <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/project-4.jpg\" alt=\"\">                    <ul>\n                                               <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/bed.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             04 Beds                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/bath.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             03 Baths                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/grage.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             02 Garage                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/size.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             1800 Sq Ft                            <\/div>\n                        <\/li>\n                                            <\/ul>\n                <\/div>\n\n                <div class=\"text\">\n                   <h2><a href=\"https:\/\/wpolive.com\/suqat\/project\/contemporary-oasis-retreat-2\/\">Contemporary Oasis Retreat<\/a><\/h2>\n                    <span>12 Avenue, New York<\/span>                <\/div>\n            <\/div>\n           \t\t\t\t\t   <div class=\"card-single\">\n                <div class=\"image\">\n                  <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/project-6.jpg\" alt=\"\">                    <ul>\n                                               <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/bed.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             04 Beds                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/bath.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             03 Baths                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/grage.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             02 Garage                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/size.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             1800 Sq Ft                            <\/div>\n                        <\/li>\n                                            <\/ul>\n                <\/div>\n\n                <div class=\"text\">\n                   <h2><a href=\"https:\/\/wpolive.com\/suqat\/project\/serenity-haven-residences\/\">Serenity Haven Residences<\/a><\/h2>\n                    <span>120 Avenue, Thailand<\/span>                <\/div>\n            <\/div>\n           \t\t\t\t\t   <div class=\"card-single\">\n                <div class=\"image\">\n                  <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/project-4.jpg\" alt=\"\">                    <ul>\n                                               <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/bed.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             04 Beds                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/bath.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             03 Baths                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/grage.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             02 Garage                            <\/div>\n                        <\/li>\n                                                <li>\n                            <div class=\"icon\">\n                              <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/size.svg\" alt=\"\">                            <\/div>\n                            <div class=\"text-dos\">\n                             1800 Sq Ft                            <\/div>\n                        <\/li>\n                                            <\/ul>\n                <\/div>\n\n                <div class=\"text\">\n                   <h2><a href=\"https:\/\/wpolive.com\/suqat\/project\/contemporary-oasis-retreat\/\">Contemporary Oasis Retreat<\/a><\/h2>\n                    <span>12 Avenue, New York<\/span>                <\/div>\n            <\/div>\n           \t       <\/div>\n\t    <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-868f466 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"868f466\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dfc229c\" data-id=\"dfc229c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-570cd21 elementor-widget elementor-widget-wpo-suqat_funfact\" data-id=\"570cd21\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_funfact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t   \r\n\t <div class=\"suqat-funfact wpo-fun-fact-section\">\r\n    \t<div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col col-xs-12\">\r\n                <div class=\"wpo-fun-fact-grids clearfix\">\r\n                                        <div class=\"grid\">\r\n                        <div class=\"info\">\r\n                        <h3><span class=\"odometer\" data-count=\"215\">00<\/span>+<\/h3><p>Current Client<\/p>                      <\/div>\r\n                    <\/div>\r\n                                       <div class=\"grid\">\r\n                        <div class=\"info\">\r\n                        <h3><span class=\"odometer\" data-count=\"50\">00<\/span>+<\/h3><p>Award Wining<\/p>                      <\/div>\r\n                    <\/div>\r\n                                       <div class=\"grid\">\r\n                        <div class=\"info\">\r\n                        <h3><span class=\"odometer\" data-count=\"15\">00<\/span>+<\/h3><p>Years of Experience<\/p>                      <\/div>\r\n                    <\/div>\r\n                                       <div class=\"grid\">\r\n                        <div class=\"info\">\r\n                        <h3><span class=\"odometer\" data-count=\"150\">00<\/span>+<\/h3><p>Property<\/p>                      <\/div>\r\n                    <\/div>\r\n                   \t               <\/div>\r\n\t            <\/div>\r\n\t          <\/div>\r\n\t        <\/div>\r\n\t    <\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e41b839 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e41b839\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9da5ac\" data-id=\"b9da5ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8eb00ba elementor-widget elementor-widget-wpo-suqat_maps\" data-id=\"8eb00ba\" data-element_type=\"widget\" data-settings=\"{&quot;map_image2&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/wpolive.com\\\/suqat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/place2.jpg&quot;,&quot;id&quot;:514,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;}}\" data-widget_type=\"wpo-suqat_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"suqat-map wpo-place-section-s2\">\n\t    <div class=\"container\">\n\t        <div class=\"place-wrap\">\n\t            <div class=\"row align-items-center\">\n\t                <div class=\"col-xl-12 col-md-12\">\n\t                    <div class=\"section-title wpo-section-title\">\n\t                      <h2>nearby <span>places of<\/span> the property<\/h2>\t                        <ul class=\"tabs\">\n\t                        \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t<li><button id=\"Location1\" class=\"tab\">school<span>- 1.8 Km<\/span><\/button><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t<li><button id=\"Location2\" class=\"tab\">restaurant <span>- 1.6 Km<\/span><\/button><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t<li><button id=\"Location3\" class=\"tab\">mosque <span>- 2.0 Km<\/span><\/button><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t<li><button id=\"Location4\" class=\"tab\">park <span>- 0.96 Km<\/span><\/button><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t<li><button id=\"Location5\" class=\"tab\">hospital <span>- 1.6 Km<\/span><\/button><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                        <\/ul>\n\t                    <\/div>\n\t                <\/div>\n\t                <div class=\"col-xl-12 col-md-12\">\n\t                    <div class=\"place-right-wrap clearfix\">\n\t                        <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/place2.jpg\" alt=\"\">\t                        <div id=\"location-wrap\">\n\n\t                        \t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"location1\" class=\"location s1 show active\">\n                                <div class=\"pin\">\n                                    <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/schol.svg\" alt=\"\">                                    <span>Corpus Christi School<\/span>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\t           \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"location2\" class=\"location s2 \">\n                                <div class=\"pin\">\n                                    <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/resturant.svg\" alt=\"\">                                    <span>Corpus Christi School<\/span>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\t           \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"location3\" class=\"location s3 \">\n                                <div class=\"pin\">\n                                    <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/mosque.svg\" alt=\"\">                                    <span>Baitun Nor Mosque<\/span>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\t           \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"location4\" class=\"location s4 \">\n                                <div class=\"pin\">\n                                    <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/park.svg\" alt=\"\">                                    <span>Baitun Nor Mosque<\/span>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\t           \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"location5\" class=\"location s5 \">\n                                <div class=\"pin\">\n                                    <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/hsp.svg\" alt=\"\">                                    <span>Baitun Nor Mosque<\/span>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\t           \t                        <\/div>\n\t                    <\/div>\n\t                <\/div>\n\t            <\/div>\n\t        <\/div>\n\t    <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a0dd93 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a0dd93\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10a31c0\" data-id=\"10a31c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84dd675 elementor-widget elementor-widget-wpo-suqat_testimonial\" data-id=\"84dd675\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"suqat-testimonials wpo-testimonial-section-s2\">\n\t    <div class=\"container\">\n\t        <div class=\"wpo-section-title-tp\">\n\t            <div class=\"row \">\n\t            \t\t                <div class=\"col-lg-7\">\n\t                    <div class=\"wpo-section-title-s2\">\n\t                       <h2>Discover the Smiles <span>Behind Our<\/span> Success.<\/h2>\t                    <\/div>\n\t                <\/div>\n\t            <\/div>\n\t        <\/div>\n\t        <div class=\"wpo-testimonial-wrap owl-carousel\">\n\n\t          \t            <div class=\"item\">\n\t                <div class=\"testimonial-top-wrap\">\n\t                    <div class=\"testimonial-left-item\">\n\t                        <div class=\"image\">\n\t                           <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Arlene-McCoy.jpg\" alt=\"\">\t                        <\/div>\n\t                        <div class=\"text\">\n\t                            <h4>Arlene McCoy<\/h4><span>Home Owner<\/span>\t                        <\/div>\n\t                    <\/div>\n\t                    <div class=\"ratting\">\n\t                        <ul>\n\t                        \t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    \t                        <\/ul>\n\t                    <\/div>\n\t                <\/div>\n\t                <div class=\"testimonial-text\">\n\t                  <p>This property is a hidden gem! From its charming curb appeal to its spacious interior, it exceeded my expectations. Immaculately maintained, with modern amenities and a tranquil backyard oasis.<\/p>\t                <\/div>\n\t            <\/div>\n\t             \t            <div class=\"item\">\n\t                <div class=\"testimonial-top-wrap\">\n\t                    <div class=\"testimonial-left-item\">\n\t                        <div class=\"image\">\n\t                           <img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/Kristin-Watson.jpg\" alt=\"\">\t                        <\/div>\n\t                        <div class=\"text\">\n\t                            <h4>Kristin Watson<\/h4><span>Home Owner<\/span>\t                        <\/div>\n\t                    <\/div>\n\t                    <div class=\"ratting\">\n\t                        <ul>\n\t                        \t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    <li><i class=\"ti-star\" aria-hidden=\"true\"><\/i><\/li>\n\t\t\t\t\t\t\t\t\t\t\t    \t                        <\/ul>\n\t                    <\/div>\n\t                <\/div>\n\t                <div class=\"testimonial-text\">\n\t                  <p>This property is a hidden gem! From its charming curb appeal to its spacious interior, it exceeded my expectations. Immaculately maintained, with modern amenities and a tranquil backyard oasis.<\/p>\t                <\/div>\n\t            <\/div>\n\t             \t        <\/div>\n\t    <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b80697e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b80697e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8db2c77\" data-id=\"8db2c77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62bae02 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"62bae02\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f61b313\" data-id=\"f61b313\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b375f62 elementor-widget elementor-widget-wpo-suqat_title\" data-id=\"b375f62\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"container\">\n\t\t\t<div class=\"row justify-content-center\">\n\t        <div class=\"col-lg-8\">\n\t            <div class=\"wpo-section-title\">\n\t               <h2>some <span>question<\/span> and answer.<\/h2>\t            <\/div>\n\t        <\/div>\n\t    <\/div>\n    <\/div>\n\t\t \t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1427765 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1427765\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ae611b\" data-id=\"3ae611b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba28fb1 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"ba28fb1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 08-05-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"211\" height=\"272\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/fae-left-1.jpg\" class=\"attachment-large size-large wp-image-697\" alt=\"\" srcset=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/fae-left-1.jpg 211w, https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/fae-left-1-116x150.jpg 116w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3dc658 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"f3dc658\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"211\" height=\"212\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/faq-left-2.jpg\" class=\"attachment-large size-large wp-image-698\" alt=\"\" srcset=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/faq-left-2.jpg 211w, https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/faq-left-2-150x150.jpg 150w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-074c628 elementor-widget-tablet__width-auto elementor-widget elementor-widget-image\" data-id=\"074c628\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"452\" height=\"305\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/faq-bottom-image-3.jpg\" class=\"attachment-large size-large wp-image-739\" alt=\"\" srcset=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/faq-bottom-image-3.jpg 452w, https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/faq-bottom-image-3-150x101.jpg 150w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29428dd\" data-id=\"29428dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2d13c7 elementor-widget elementor-widget-wpo-suqat_accordion\" data-id=\"a2d13c7\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpo-faq-section\">\n\t\t\t<div class=\"accordion\" id=\"accordionExample\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item\">\n\t\t\t\t\t\t\t<h3 class=\"accordion-header\" id=\"heading26a576324dfb91\"><button class=\"accordion-button \" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse26a576324dfb91\" aria-expanded=\"true\" aria-controls=\"collapse26a576324dfb91\">\n\t              01. What does your single property company specialize in?<\/button><\/h3>\t\t\t\t\t\t\t\t<div id=\"collapse26a576324dfb91\" class=\"accordion-collapse collapse show\" aria-labelledby=\"heading26a576324dfb91\" data-bs-parent=\"#accordionExample\">\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t\t\t<p>We focus on acquiring, managing, and optimizing single-family homes for rental income and long-term capital appreciation. Our expertise lies in selecting promising properties, enhancing their value, and providing excellent rental experiences for tenants.<\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item\">\n\t\t\t\t\t\t\t<h3 class=\"accordion-header\" id=\"heading36a576324dfb91\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse36a576324dfb91\" aria-expanded=\"true\" aria-controls=\"collapse36a576324dfb91\">\n\t              02. Do you have a portfolio of properties available for sale or rent?<\/button><\/h3>\t\t\t\t\t\t\t\t<div id=\"collapse36a576324dfb91\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading36a576324dfb91\" data-bs-parent=\"#accordionExample\">\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t\t\t<p>We focus on acquiring, managing, and optimizing single-family homes for rental income and long-term capital appreciation. Our expertise lies in selecting promising properties, enhancing their value, and providing excellent rental experiences for tenants.<\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item\">\n\t\t\t\t\t\t\t<h3 class=\"accordion-header\" id=\"heading46a576324dfb91\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse46a576324dfb91\" aria-expanded=\"true\" aria-controls=\"collapse46a576324dfb91\">\n\t              03. Can your company help with legal processes?<\/button><\/h3>\t\t\t\t\t\t\t\t<div id=\"collapse46a576324dfb91\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading46a576324dfb91\" data-bs-parent=\"#accordionExample\">\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t\t\t<p>We focus on acquiring, managing, and optimizing single-family homes for rental income and long-term capital appreciation. Our expertise lies in selecting promising properties, enhancing their value, and providing excellent rental experiences for tenants.<\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item\">\n\t\t\t\t\t\t\t<h3 class=\"accordion-header\" id=\"heading56a576324dfb91\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse56a576324dfb91\" aria-expanded=\"true\" aria-controls=\"collapse56a576324dfb91\">\n\t              04. How can I get in touch with your company for property inquiries?<\/button><\/h3>\t\t\t\t\t\t\t\t<div id=\"collapse56a576324dfb91\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading56a576324dfb91\" data-bs-parent=\"#accordionExample\">\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t\t\t<p>We focus on acquiring, managing, and optimizing single-family homes for rental income and long-term capital appreciation. Our expertise lies in selecting promising properties, enhancing their value, and providing excellent rental experiences for tenants.<\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item\">\n\t\t\t\t\t\t\t<h3 class=\"accordion-header\" id=\"heading66a576324dfb91\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse66a576324dfb91\" aria-expanded=\"true\" aria-controls=\"collapse66a576324dfb91\">\n\t              05. What does your company specialize in?<\/button><\/h3>\t\t\t\t\t\t\t\t<div id=\"collapse66a576324dfb91\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading66a576324dfb91\" data-bs-parent=\"#accordionExample\">\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t\t\t<p>We focus on acquiring, managing, and optimizing single-family homes for rental income and long-term capital appreciation. Our expertise lies in selecting promising properties, enhancing their value, and providing excellent rental experiences for tenants.<\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item\">\n\t\t\t\t\t\t\t<h3 class=\"accordion-header\" id=\"heading76a576324dfb91\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse76a576324dfb91\" aria-expanded=\"true\" aria-controls=\"collapse76a576324dfb91\">\n\t              06. What marketing strategies do you use?<\/button><\/h3>\t\t\t\t\t\t\t\t<div id=\"collapse76a576324dfb91\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading76a576324dfb91\" data-bs-parent=\"#accordionExample\">\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t\t\t<p>We focus on acquiring, managing, and optimizing single-family homes for rental income and long-term capital appreciation. Our expertise lies in selecting promising properties, enhancing their value, and providing excellent rental experiences for tenants.<\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b2861 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"86b2861\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e4cf30d\" data-id=\"e4cf30d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14574ce elementor-widget elementor-widget-wpo-suqat_blog\" data-id=\"14574ce\" data-element_type=\"widget\" data-widget_type=\"wpo-suqat_blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"suqat-blog wpo-blog-section-s2\">\n\t\t\t<div class=\" container\">\n\t\t\t\t<div class=\"blog-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"col-xl-7 col-lg-5\">\n\t\t\t\t\t\t<div class=\"wpo-section-title-s2\">\n\t\t\t\t\t\t\t<h2>check our <span>latest blog<\/span> and article.<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"blog-slide-active owl-carousel\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-item s2\">\n\t\t\t\t\t\t\t\t<div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/grid-post-3.jpg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t<span>September 13, 2023<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\t\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/trends-and-innovations-shaping-the-industry\/\">\n\t\t\t\t\t\t\t\t\t\t\tTrends and Innovations Shaping the Industry.\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t <a href=\"https:\/\/wpolive.com\/suqat\/trends-and-innovations-shaping-the-industry\/\" class=\"read-more\">Read More<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-item s2\">\n\t\t\t\t\t\t\t\t<div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/grid-post-2.jpg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t<span>September 13, 2023<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\t\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/how-architects-design-for-less-lonely-living\/\">\n\t\t\t\t\t\t\t\t\t\t\tHow Architects Design for Less Lonely Living\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t <a href=\"https:\/\/wpolive.com\/suqat\/how-architects-design-for-less-lonely-living\/\" class=\"read-more\">Read More<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-item s2\">\n\t\t\t\t\t\t\t\t<div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wpolive.com\/suqat\/wp-content\/uploads\/2023\/09\/grid-post-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t<span>September 13, 2023<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\t\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wpolive.com\/suqat\/making-informed-decisions-for-home-financing\/\">\n\t\t\t\t\t\t\t\t\t\t\tMaking Informed Decisions for Home Financing.\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t <a href=\"https:\/\/wpolive.com\/suqat\/making-informed-decisions-for-home-financing\/\" class=\"read-more\">Read More<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"Tucson, Arizona(AZ), 85719 Your Exclusive Haven of Luxury and Comfort get started Tucson, Arizona(AZ), 85719 Your Exclusive Haven of Luxury and Comfort get started Tucson, Arizona(AZ), 85719 Your Exclusive Haven of Luxury and Comfort get started Watch Intro Video 5 bed room 2 full baths 4 half baths 2 car parking 6,382 square feet take ","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"footnotes":""},"_links":{"self":[{"href":"https:\/\/wpolive.com\/suqat\/wp-json\/wp\/v2\/pages\/82"}],"collection":[{"href":"https:\/\/wpolive.com\/suqat\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wpolive.com\/suqat\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wpolive.com\/suqat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wpolive.com\/suqat\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":0,"href":"https:\/\/wpolive.com\/suqat\/wp-json\/wp\/v2\/pages\/82\/revisions"}],"wp:attachment":[{"href":"https:\/\/wpolive.com\/suqat\/wp-json\/wp\/v2\/media?parent=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}